{"id":40197,"date":"2022-08-26T11:10:06","date_gmt":"2022-08-26T09:10:06","guid":{"rendered":"https:\/\/funbridge.com\/blog\/?p=40197"},"modified":"2025-07-03T13:55:38","modified_gmt":"2025-07-03T12:55:38","slug":"what-is-he-calling-for","status":"publish","type":"post","link":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/","title":{"rendered":"Pourquoi est-ce qu&#8217;il appelle&nbsp;?"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1-1024x576.jpg\" alt=\"\" class=\"wp-image-49756\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1-1024x576.jpg 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1-300x169.jpg 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1-768x432.jpg 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1-1536x864.jpg 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>L&#8217;\u00e9ternelle question pour un joueur de bridge&#8230; Qui est fautif ? Qui est coupable ? Cet article porte sur un sujet qui est source de nombreuses discussions \u00e0 la fin des tournois : la signalisation.<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>P\u00e9riode de confinement g\u00e9n\u00e9ral. ll est 17h00, l&#8217;heure de s&#8217;asseoir pour jouer le duplicate d&#8217;entra\u00eenement quotidien sur BBO. En Est-Ouest une paire compos\u00e9e de deux jeunes joueurs qui cherchent \u00e0 obtenir une place aux tournois mixtes \u00e0 venir. En Sud un petit requin habitu\u00e9 des salles en ligne qui prend plaisir \u00e0 mettre tout le monde \u00e0 la table sur une fausse piste, \u00e0 commencer par son partenaire, s\u00e9rieux et bien \u00e9duqu\u00e9.<\/p>\n\n\n\n<p>Apr\u00e8s deux donnes banales, voici le diagramme qui appara\u00eet \u00e0 l&#8217;\u00e9cran : <\/p>\n\n\n\n<p>Donne 3. Donneur Sud. Nord-Sud vuln\u00e9rables.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/pourquoi-est-ce-qu-il-appelle-1-1024x934.jpg\" alt=\"\" class=\"wp-image-49745\" width=\"512\" height=\"467\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/pourquoi-est-ce-qu-il-appelle-1-1024x934.jpg 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/pourquoi-est-ce-qu-il-appelle-1-300x274.jpg 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/pourquoi-est-ce-qu-il-appelle-1-768x700.jpg 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/pourquoi-est-ce-qu-il-appelle-1-1536x1401.jpg 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/pourquoi-est-ce-qu-il-appelle-1-2048x1868.jpg 2048w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il n&#8217;y a pas grand-chose \u00e0 dire sur les ench\u00e8res :<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image2-4-1024x515.jpg\" alt=\"\" class=\"wp-image-49783\" width=\"768\" height=\"386\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image2-4-1024x515.jpg 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image2-4-300x151.jpg 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image2-4-768x386.jpg 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image2-4-1536x772.jpg 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image2-4-2048x1029.jpg 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La jeune femme entame l&#8217;As de C\u0153ur, comme il convient de le faire, qui est suivi du 6 au mort, du 2 et de la Dame. Apr\u00e8s un moment de r\u00e9flexion, elle change de couleur et joue le 9 de Tr\u00e8fle. B\u00e9b\u00e9 requin remporte la lev\u00e9e avec la Dame. M\u00eame sur BBO, sa fa\u00e7on de ramasser la lev\u00e9e ne laisse aucun doute quant \u00e0 sa satisfaction. Apr\u00e8s avoir fait tomber les atouts, il joue un C\u0153ur pour affranchir sa 10\u00e8me lev\u00e9e : il a 5 Piques, 2 lev\u00e9es dans chaque mineure et 1 C\u0153ur. <\/p>\n\n\n\n<p>Pas de mouvement d&#8217;humeur, pas de commentaire dans la fen\u00eatre de chat de l&#8217;un des deux partenaires de notre future paire en mixte. Mais quand un nouveau diagramme appara\u00eet, la jeune femme met du temps \u00e0 ench\u00e9rir.<\/p>\n\n\n\n<p>Les protagonistes de la salle ne le savent pas plus que les quelques spectateurs, mais son partenaire n&#8217;a pas pu s&#8217;emp\u00eacher de l&#8217;appeler sur son t\u00e9l\u00e9phone. Et la discussion a \u00e9t\u00e9 tout sauf calme :<\/p>\n\n\n\n<p>&#8211; &#8220;S\u00e9rieusement, quelle id\u00e9e d&#8217;entamer sous ton Roi de Tr\u00e8fle ! Je comprends que tu puisses \u00eatre r\u00e9ticente \u00e0 continuer \u00e0 C\u0153ur, mais tu peux jouer \u00e0 Carreau sans aucun risque. Enfin bon !&#8221;<\/p>\n\n\n\n<p>&#8211; &#8220;Ecoute, tu as fait un refus \u00e0 C\u0153ur. J&#8217;ai pens\u00e9 qu&#8217;on avait besoin de 3 lev\u00e9es \u00e0 Tr\u00e8fle pour battre le contrat donc j&#8217;ai jou\u00e9 un Tr\u00e8fle&#8230; Je suis d\u00e9sol\u00e9e. Mais comme tu es si intelligent, peux-tu m&#8217;expliquer comment j&#8217;aurais pu deviner ?&#8221;<\/p>\n\n\n\n<p><strong>C&#8217;est \u00e0 votre tour, cher lecteur. Les th\u00e9ories de la jeune femme sont-elles d\u00e9fendables ? La col\u00e8re du jeune homme est-elle justifi\u00e9e ? Y avait-il une autre solution ? En un mot, qui est responsable de cette catastrophe ? La jeune femme, le jeune homme ou le destin ?<\/strong><\/p>\n\n\n\n\n\n\n<p>Examinons d&#8217;abord le raisonnement de notre jeune femme. Elle a besoin de 4 lev\u00e9es pour battre le contrat. M\u00eame si la carte de Sud n&#8217;est pas honn\u00eate, on peut compter sur 2 C\u0153urs. Quid des deux autres ? Il semble bien que les Tr\u00e8fles soient les meilleurs candidats. Mais est-il vraiment urgent de jouer dans cette couleur ? Regardons de plus pr\u00e8s :<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image3-6-1024x934.jpg\" alt=\"\" class=\"wp-image-49785\" width=\"512\" height=\"467\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image3-6-1024x934.jpg 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image3-6-300x274.jpg 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image3-6-768x700.jpg 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image3-6-1536x1401.jpg 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/FR-image3-6-2048x1868.jpg 2048w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si la jeune femme suit la recommandation de son partenaire et joue \u00e0 Carreau, Sud ne fera plus 10 lev\u00e9es mais 11 ! Cette fois, la seule d\u00e9fense pour battre le contrat est vraiment d&#8217;attaquer les Tr\u00e8fles avant que Sud n&#8217;affranchisse sa 10\u00e8me lev\u00e9e \u00e0 C\u0153ur. Donc&#8230; Si on d\u00e9cide de lui pardonner, doit-on en conclure que la donne est trop difficile et la ranger dans le tiroir des d\u00e9fenses introuvables ? Mais est-on toujours int\u00e9ress\u00e9 \u00e0 la place de notre beau jeune homme (Je ne vous ai pas dit qu&#8217;il \u00e9tait charmant ? Vous l&#8217;aviez compris de toute fa\u00e7on. Soit dit en passant, la jeune femme n&#8217;est pas mal non plus&#8230;). Selon lui, y a-t-il un int\u00e9r\u00eat \u00e0 ce qu&#8217;Ouest joue autre chose qu&#8217;\u00e0 C\u0153ur ? Jouer \u00e0 Carreau est assur\u00e9ment correct, peut-\u00eatre m\u00eame utile de temps en temps, mais il n&#8217;y a absolument rien d&#8217;urgent \u00e0 le faire. D&#8217;un autre c\u00f4t\u00e9, jouer \u00e0 Tr\u00e8fle semble tout droit vou\u00e9 au d\u00e9sastre. Et ces Tr\u00e8fles sont la couleur normale pour un changement du point de vue d&#8217;Ouest : les fameuses trois petites cartes qu&#8217;on nous dit d&#8217;attaquer quand il semble urgent de ramasser des lev\u00e9es pour la d\u00e9fense. Est aurait pu (d\u00fb ?) anticiper le probl\u00e8me de sa partenaire et <strong>encourager une continuation \u00e0 C\u0153ur<\/strong>. Apr\u00e8s tout, &#8220;encourager&#8221; signifie dire \u00e0 son partenaire qu&#8217;on pense que jouer \u00e0 C\u0153ur est dans l&#8217;int\u00e9r\u00eat de notre camp. C&#8217;est exactement l&#8217;id\u00e9e qu&#8217;aurait d\u00fb avoir Est.<\/p>\n\n\n\n<p>Mais ne nous y trompons pas. Sur le deuxi\u00e8me diagramme, Est peut tranquillement d\u00e9courager \u00e0 C\u0153ur car sa Dame de Tr\u00e8fle lui permet de soutenir un changement de couleur en faveur des Tr\u00e8fles, qui serait fatal pour le d\u00e9clarant&#8230;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>A retenir<\/strong><\/p><p>D\u00e9courager la poursuite d&#8217;une couleur revient \u00e0 sugg\u00e9rer &#8211; ou du moins accepter &#8211; que le partenaire joue dans une autre couleur.<br>Quand changer pour jouer dans la couleur &#8220;normale&#8221; semble une mauvaise id\u00e9e, vous devez encourager la couleur jou\u00e9e, y compris quand vous avez trois petites cartes.<\/p><\/blockquote>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu&#8217;avez-vous pens\u00e9 de cet article de Philippe Cronier ?<\/strong><\/h2>\n\n\n\n<p>Partagez votre avis avec d&#8217;autres bridgeurs dans la section <em>Commentaires<\/em> ci-dessous !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9ternelle question pour un joueur de bridge&#8230; Qui est fautif ? Qui est coupable ? Cet article porte sur un sujet qui est source de nombreuses discussions \u00e0 la fin des tournois : la signalisation. P\u00e9riode de confinement g\u00e9n\u00e9ral. ll est 17h00, l&#8217;heure de s&#8217;asseoir pour jouer le duplicate d&#8217;entra\u00eenement quotidien sur BBO. En Est-Ouest une paire compos\u00e9e de deux jeunes joueurs qui cherchent \u00e0 obtenir une place aux tournois mixtes \u00e0 venir. En Sud un petit requin habitu\u00e9 des salles en ligne qui prend plaisir \u00e0 mettre tout le monde \u00e0 la table sur une fausse piste, \u00e0 commencer\u2026<\/p>\n","protected":false},"author":37,"featured_media":49756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14921],"tags":[1638],"access":[13325],"class_list":["post-40197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cours-exercices-bridge","tag-analyse-de-donnes","access-premium-plus"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":5}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pourquoi est-ce qu&#039;il appelle ? - Blog Funbridge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pourquoi est-ce qu&#039;il appelle ? - Blog Funbridge\" \/>\n<meta property=\"og:description\" content=\"L&#8217;\u00e9ternelle question pour un joueur de bridge&#8230; Qui est fautif ? Qui est coupable ? Cet article porte sur un sujet qui est source de nombreuses discussions \u00e0 la fin des tournois : la signalisation. P\u00e9riode de confinement g\u00e9n\u00e9ral. ll est 17h00, l&#8217;heure de s&#8217;asseoir pour jouer le duplicate d&#8217;entra\u00eenement quotidien sur BBO. En Est-Ouest une paire compos\u00e9e de deux jeunes joueurs qui cherchent \u00e0 obtenir une place aux tournois mixtes \u00e0 venir. En Sud un petit requin habitu\u00e9 des salles en ligne qui prend plaisir \u00e0 mettre tout le monde \u00e0 la table sur une fausse piste, \u00e0 commencer\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Funbridge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Funbridge\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-26T09:10:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T12:55:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe Cronier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@funbridge\" \/>\n<meta name=\"twitter:site\" content=\"@funbridge\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philippe Cronier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/\"},\"author\":{\"name\":\"Philippe Cronier\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85\"},\"headline\":\"Pourquoi est-ce qu&#8217;il appelle&nbsp;?\",\"datePublished\":\"2022-08-26T09:10:06+00:00\",\"dateModified\":\"2025-07-03T12:55:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/\"},\"wordCount\":874,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg\",\"keywords\":[\"analyse de donnes\"],\"articleSection\":[\"Cours et exercices de bridge\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/\",\"url\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/\",\"name\":\"Pourquoi est-ce qu'il appelle ? - Blog Funbridge\",\"isPartOf\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg\",\"datePublished\":\"2022-08-26T09:10:06+00:00\",\"dateModified\":\"2025-07-03T12:55:38+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage\",\"url\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg\",\"contentUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Whose fault by Philippe Cronier\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/funbridge.com\/blog\/#website\",\"url\":\"https:\/\/funbridge.com\/blog\/\",\"name\":\"Blog Funbridge\",\"description\":\"Toute l&#039;actualit\u00e9 du bridge et de FunBridge en un clin d&#039;\u0153il\",\"publisher\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/funbridge.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/funbridge.com\/blog\/#organization\",\"name\":\"Funbridge\",\"url\":\"https:\/\/funbridge.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png\",\"contentUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png\",\"width\":610,\"height\":148,\"caption\":\"Funbridge\"},\"image\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Funbridge\/\",\"https:\/\/x.com\/funbridge\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85\",\"name\":\"Philippe Cronier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png\",\"contentUrl\":\"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png\",\"caption\":\"Philippe Cronier\"},\"description\":\"Ce joueur redoutable est n\u00e9 \u00e0 Ermont, pr\u00e8s de Paris. Il a \u00e9t\u00e9 le directeur p\u00e9dagogique de l\u2019Universit\u00e9 du bridge pendant 20 ans. Champion d\u2019Europe par \u00e9quipes, champion du monde seniors, il a \u00e9t\u00e9 sacr\u00e9 champion du monde par \u00e9quipes mixtes en 2022. Plus qu\u2019un joueur, il est aussi journaliste pour Le Bridgeur.\",\"url\":\"https:\/\/funbridge.com\/blog\/author\/pcronier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pourquoi est-ce qu'il appelle ? - Blog Funbridge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/","og_locale":"fr_FR","og_type":"article","og_title":"Pourquoi est-ce qu'il appelle ? - Blog Funbridge","og_description":"L&#8217;\u00e9ternelle question pour un joueur de bridge&#8230; Qui est fautif ? Qui est coupable ? Cet article porte sur un sujet qui est source de nombreuses discussions \u00e0 la fin des tournois : la signalisation. P\u00e9riode de confinement g\u00e9n\u00e9ral. ll est 17h00, l&#8217;heure de s&#8217;asseoir pour jouer le duplicate d&#8217;entra\u00eenement quotidien sur BBO. En Est-Ouest une paire compos\u00e9e de deux jeunes joueurs qui cherchent \u00e0 obtenir une place aux tournois mixtes \u00e0 venir. En Sud un petit requin habitu\u00e9 des salles en ligne qui prend plaisir \u00e0 mettre tout le monde \u00e0 la table sur une fausse piste, \u00e0 commencer\u2026","og_url":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/","og_site_name":"Blog Funbridge","article_publisher":"https:\/\/www.facebook.com\/Funbridge\/","article_published_time":"2022-08-26T09:10:06+00:00","article_modified_time":"2025-07-03T12:55:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg","type":"image\/jpeg"}],"author":"Philippe Cronier","twitter_card":"summary_large_image","twitter_creator":"@funbridge","twitter_site":"@funbridge","twitter_misc":{"\u00c9crit par":"Philippe Cronier","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#article","isPartOf":{"@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/"},"author":{"name":"Philippe Cronier","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85"},"headline":"Pourquoi est-ce qu&#8217;il appelle&nbsp;?","datePublished":"2022-08-26T09:10:06+00:00","dateModified":"2025-07-03T12:55:38+00:00","mainEntityOfPage":{"@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/"},"wordCount":874,"commentCount":6,"publisher":{"@id":"https:\/\/funbridge.com\/blog\/#organization"},"image":{"@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage"},"thumbnailUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg","keywords":["analyse de donnes"],"articleSection":["Cours et exercices de bridge"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/","url":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/","name":"Pourquoi est-ce qu'il appelle ? - Blog Funbridge","isPartOf":{"@id":"https:\/\/funbridge.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage"},"image":{"@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage"},"thumbnailUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg","datePublished":"2022-08-26T09:10:06+00:00","dateModified":"2025-07-03T12:55:38+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/funbridge.com\/blog\/fr\/what-is-he-calling-for\/#primaryimage","url":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg","contentUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-philippe-cronier-1.jpg","width":1920,"height":1080,"caption":"Whose fault by Philippe Cronier"},{"@type":"WebSite","@id":"https:\/\/funbridge.com\/blog\/#website","url":"https:\/\/funbridge.com\/blog\/","name":"Blog Funbridge","description":"Toute l&#039;actualit\u00e9 du bridge et de FunBridge en un clin d&#039;\u0153il","publisher":{"@id":"https:\/\/funbridge.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/funbridge.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/funbridge.com\/blog\/#organization","name":"Funbridge","url":"https:\/\/funbridge.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png","contentUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png","width":610,"height":148,"caption":"Funbridge"},"image":{"@id":"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Funbridge\/","https:\/\/x.com\/funbridge"]},{"@type":"Person","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85","name":"Philippe Cronier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png","contentUrl":"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png","caption":"Philippe Cronier"},"description":"Ce joueur redoutable est n\u00e9 \u00e0 Ermont, pr\u00e8s de Paris. Il a \u00e9t\u00e9 le directeur p\u00e9dagogique de l\u2019Universit\u00e9 du bridge pendant 20 ans. Champion d\u2019Europe par \u00e9quipes, champion du monde seniors, il a \u00e9t\u00e9 sacr\u00e9 champion du monde par \u00e9quipes mixtes en 2022. Plus qu\u2019un joueur, il est aussi journaliste pour Le Bridgeur.","url":"https:\/\/funbridge.com\/blog\/author\/pcronier\/"}]}},"lang":"fr","translations":{"fr":40197,"en":40206},"language":"fr","pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts\/40197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/comments?post=40197"}],"version-history":[{"count":53,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts\/40197\/revisions"}],"predecessor-version":[{"id":49790,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts\/40197\/revisions\/49790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/media\/49756"}],"wp:attachment":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/media?parent=40197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/categories?post=40197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/tags?post=40197"},{"taxonomy":"access","embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/access?post=40197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}