{"id":52122,"date":"2022-10-03T06:30:00","date_gmt":"2022-10-03T04:30:00","guid":{"rendered":"https:\/\/funbridge.com\/blog\/?p=52122"},"modified":"2025-07-03T13:50:30","modified_gmt":"2025-07-03T12:50:30","slug":"whose-fault","status":"publish","type":"post","link":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/","title":{"rendered":"Un appel, \u00e7a&nbsp;?"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-1024x576.jpg\" alt=\"\" class=\"wp-image-52126\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-1024x576.jpg 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-300x169.jpg 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-768x432.jpg 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault-1536x864.jpg 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p><strong>\u00c9ternelle question du bridgeur&#8230; \u00e0 qui la faute, quel est le coupable ? Cet article est d\u00e9di\u00e9 \u00e0 un domaine pr\u00e9texte \u00e0 bien des discussions au sortir des tournois, la signalisation.<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il est 17 heures, l\u2019heure de prendre place pour le duplicate d\u2019entra\u00eenement quotidien en ligne. En Est-Ouest, un couple encore jeune qui vise \u00e0 bien figurer dans les prochaines \u00e9preuves mixtes. En Sud, un petit requin des salles num\u00e9riques qui prend un malin plaisir \u00e0 mystifier tout le monde \u00e0 la table, \u00e0 commencer par son partenaire, s\u00e9rieux et bien \u00e9lev\u00e9.<\/p>\n\n\n\n<p>Apr\u00e8s deux donnes banales, voici le diagramme qui s\u2019affiche \u00e0 l\u2019\u00e9cran:Donne 3, Sud donneur, Nord-Sud vuln\u00e9rables.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-1-1024x934.png\" alt=\"\" class=\"wp-image-52138\" width=\"512\" height=\"467\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-1-1024x934.png 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-1-300x274.png 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-1-768x700.png 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-1-1536x1401.png 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-1-2048x1868.png 2048w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il n\u2019y a pas grand-chose \u00e0 dire des ench\u00e8res:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-2-1024x515.png\" alt=\"\" class=\"wp-image-52139\" width=\"512\" height=\"258\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-2-1024x515.png 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-2-300x151.png 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-2-768x386.png 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-2-1536x772.png 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-2-2048x1029.png 2048w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La Jeune femme entame d\u00fbment de l\u2019As de C\u0153ur sur lequel apparaissent successivement le 6 du mort, le 2 et la Dame. Apr\u00e8s quelques instants de r\u00e9flexion, la Jeune femme rejoue le 9 de Tr\u00e8fle. B\u00e9b\u00e9 requin fait la lev\u00e9e de la Dame. M\u00eame en ligne, sa fa\u00e7on de ramasser la lev\u00e9e ne laisse planer aucune ambigu\u00eft\u00e9 sur sa satisfaction. Apr\u00e8s avoir enlev\u00e9 les atouts, il rejoue C\u0153ur pour affranchir sa dixi\u00e8me lev\u00e9e : il a r\u00e9alis\u00e9 cinq Piques, deux lev\u00e9es dans chaque mineure et une lev\u00e9e \u00e0 C\u0153ur. Nulle marque d\u2019humeur, nulle r\u00e9flexion sur la fen\u00eatre de chat de l\u2019un des deux partenaires de notre paire mixte en devenir. Mais tandis qu\u2019un nouveau diagramme appara\u00eet, la Jeune femme tarde \u00e0 ench\u00e9rir.<\/p>\n\n\n\n<p>Les protagonistes de la salle ne le savent pas plus que les quelques spectateurs, mais son partenaire n\u2019a pas r\u00e9sist\u00e9 \u00e0 l\u2019envie de l\u2019appeler au t\u00e9l\u00e9phone. Et la discussion n\u2019est pas tr\u00e8s am\u00e8ne.<\/p>\n\n\n\n<p>&#8211; \u00abVraiment, quelle id\u00e9e de rejouer sous ton Roi de Tr\u00e8fle ! Je comprends que tu puisses avoir une r\u00e9ticence \u00e0 continuer \u00e0 C\u0153ur mais tu peux contre-attaquer \u00e0 Carreau sans risque, quand m\u00eame !\u00bb<\/p>\n\n\n\n<p>&#8211; \u00ab\u00c9coute, tu as refus\u00e9 les C\u0153urs, j\u2019ai pens\u00e9 qu\u2019il fallait faire trois lev\u00e9es de Tr\u00e8fle pour battre le contrat, j\u2019en ai rejou\u00e9&#8230; Excuse-moi, mais toi qui es si malin, tu veux bien m\u2019expliquer comment je pouvais savoir ?\u00bb<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>C\u2019est \u00e0 vous, maintenant, cher lecteur. Les th\u00e8ses de la Jeune femme sont-elles d\u00e9fendables ? Le courroux du Jeune homme est-il justifi\u00e9 ? Y avait-il une fa\u00e7on diff\u00e9rente de s\u2019en sortir ? En un mot, \u00e0 qui incombe la catastrophe ? Madame, monsieur, ou le Destin ?<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n\n<p>Int\u00e9ressons-nous d\u2019abord au mode de pens\u00e9e de notre Jeune femme. Il lui faut trouver quatre lev\u00e9es pour battre. M\u00eame si la carte de Sud n\u2019est pas sinc\u00e8re, nous pouvons compter sur deux C\u0153urs. Quid des deux autres ? Il semble bien que les Tr\u00e8fles soient les meilleurs candidats. Y a-t-il vraiment urgence \u00e0 jouer la couleur? Regardez mieux :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-3-1024x934.png\" alt=\"\" class=\"wp-image-52140\" width=\"512\" height=\"467\" srcset=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-3-1024x934.png 1024w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-3-300x274.png 300w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-3-768x700.png 768w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-3-1536x1401.png 1536w, https:\/\/funbridge.com\/blog\/wp-content\/uploads\/un-appel-ca-article-de-bridge-philippe-cronier-3-2048x1868.png 2048w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<p>Si la Jeune femme suit la pr\u00e9conisation de son partenaire et contre-attaque \u00e0 Carreau, ce ne sont plus dix lev\u00e9es que Sud va r\u00e9aliser, mais onze ! Cette fois, le seul flanc pour battre consiste bien \u00e0 attaquer les Tr\u00e8fles, avant que Sud ne puisse \u00e9tablir sa dixi\u00e8me lev\u00e9e \u00e0 C\u0153ur. Alors&#8230; si nous d\u00e9cidons de l\u2019absoudre, faut-il conclure que la donne est trop difficile et la ranger dans le tiroir des d\u00e9fenses introuvables?<\/p>\n\n\n\n<p>Int\u00e9ressons-nous malgr\u00e9 tout au cas de notre s\u00e9duisant Jeune homme ( je ne vous avais pas dit qu\u2019il \u00e9tait s\u00e9duisant? Vous l\u2019aviez compris. D\u2019ailleurs, la Jeune femme n\u2019est pas mal non plus&#8230;). De son point de vue, y a-t-il un int\u00e9r\u00eat \u00e0 ce que Ouest joue autre chose que C\u0153ur? Le flanc \u00e0 Carreau est sans doute correct, peut-\u00eatre m\u00eame utile de temps en temps, mais n\u2019a absolument rien d\u2019urgent. En revanche, la contre-attaque \u00e0 Tr\u00e8fle semble bien pouvoir tourner \u00e0 la catastrophe. Et ces Tr\u00e8fles constituent la couleur normale de la contre-attaque d\u2019Ouest, ces fameuses trois petites cartes qu\u2019on nous dit d\u2019attaquer quand il semble qu\u2019il y ait une urgence. Est aurait pu (d\u00fb?) anticiper le probl\u00e8me de sa partenaire <strong>en appelant \u00e0 C\u0153ur.<\/strong> Apr\u00e8s tout, \u201cappeler\u201d consiste bien \u00e0 dire qu\u2019on pense que jouer C\u0153ur est bon pour les int\u00e9r\u00eats de son camp. C\u2019est exactement l\u2019id\u00e9e qu\u2019Est aurait d\u00fb avoir.<\/p>\n\n\n\n<p>Ne nous m\u00e9prenons pas : dans le second diagramme, Est peut tranquillement refuser les C\u0153urs, sa Dame de Tr\u00e8fle lui permettant de supporter le retour \u00e0 Tr\u00e8fle, qui s\u2019av\u00e9rera mortel pour le d\u00e9clarant&#8230;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Rappelez-vous<\/strong><\/p><p>\u00b7 Le refus d\u2019une couleur correspond souvent \u00e0 sugg\u00e9rer, ou du moins accepter que le partenaire en joue une autre.<\/p><p>\u00b7 Quand il semble que la contre-attaque dans la couleur \u201cnormale\u201d soit une mauvaise id\u00e9e, il faut appeler dans la couleur jou\u00e9e, y compris avec trois petits.<\/p><\/blockquote>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Que pensez-vous de cet article de Philippe Cronier ?<\/strong><\/h2>\n\n\n\n<p>Partagez votre opinion avec les autres <em>Funbridgeurs<\/em> dans la section Commentaires ci-dessous !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9ternelle question du bridgeur&#8230; \u00e0 qui la faute, quel est le coupable ? Cet article est d\u00e9di\u00e9 \u00e0 un domaine pr\u00e9texte \u00e0 bien des discussions au sortir des tournois, la signalisation. Il est 17 heures, l\u2019heure de prendre place pour le duplicate d\u2019entra\u00eenement quotidien en ligne. En Est-Ouest, un couple encore jeune qui vise \u00e0 bien figurer dans les prochaines \u00e9preuves mixtes. En Sud, un petit requin des salles num\u00e9riques qui prend un malin plaisir \u00e0 mystifier tout le monde \u00e0 la table, \u00e0 commencer par son partenaire, s\u00e9rieux et bien \u00e9lev\u00e9. Apr\u00e8s deux donnes banales, voici le diagramme qui\u2026<\/p>\n","protected":false},"author":37,"featured_media":52126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14921],"tags":[1638],"access":[13325],"class_list":["post-52122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cours-exercices-bridge","tag-analyse-de-donnes","access-premium-plus"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":5}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un appel, \u00e7a ? - Blog Funbridge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un appel, \u00e7a ? - Blog Funbridge\" \/>\n<meta property=\"og:description\" content=\"\u00c9ternelle question du bridgeur&#8230; \u00e0 qui la faute, quel est le coupable ? Cet article est d\u00e9di\u00e9 \u00e0 un domaine pr\u00e9texte \u00e0 bien des discussions au sortir des tournois, la signalisation. Il est 17 heures, l\u2019heure de prendre place pour le duplicate d\u2019entra\u00eenement quotidien en ligne. En Est-Ouest, un couple encore jeune qui vise \u00e0 bien figurer dans les prochaines \u00e9preuves mixtes. En Sud, un petit requin des salles num\u00e9riques qui prend un malin plaisir \u00e0 mystifier tout le monde \u00e0 la table, \u00e0 commencer par son partenaire, s\u00e9rieux et bien \u00e9lev\u00e9. Apr\u00e8s deux donnes banales, voici le diagramme qui\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Funbridge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Funbridge\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-03T04:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T12:50:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe Cronier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@funbridge\" \/>\n<meta name=\"twitter:site\" content=\"@funbridge\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philippe Cronier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/\"},\"author\":{\"name\":\"Philippe Cronier\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85\"},\"headline\":\"Un appel, \u00e7a&nbsp;?\",\"datePublished\":\"2022-10-03T04:30:00+00:00\",\"dateModified\":\"2025-07-03T12:50:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/\"},\"wordCount\":861,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg\",\"keywords\":[\"analyse de donnes\"],\"articleSection\":[\"Cours et exercices de bridge\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/\",\"url\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/\",\"name\":\"Un appel, \u00e7a ? - Blog Funbridge\",\"isPartOf\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg\",\"datePublished\":\"2022-10-03T04:30:00+00:00\",\"dateModified\":\"2025-07-03T12:50:30+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage\",\"url\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg\",\"contentUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Whose fault\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/funbridge.com\/blog\/#website\",\"url\":\"https:\/\/funbridge.com\/blog\/\",\"name\":\"Blog Funbridge\",\"description\":\"Toute l&#039;actualit\u00e9 du bridge et de FunBridge en un clin d&#039;\u0153il\",\"publisher\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/funbridge.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/funbridge.com\/blog\/#organization\",\"name\":\"Funbridge\",\"url\":\"https:\/\/funbridge.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png\",\"contentUrl\":\"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png\",\"width\":610,\"height\":148,\"caption\":\"Funbridge\"},\"image\":{\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Funbridge\/\",\"https:\/\/x.com\/funbridge\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85\",\"name\":\"Philippe Cronier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/funbridge.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png\",\"contentUrl\":\"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png\",\"caption\":\"Philippe Cronier\"},\"description\":\"Ce joueur redoutable est n\u00e9 \u00e0 Ermont, pr\u00e8s de Paris. Il a \u00e9t\u00e9 le directeur p\u00e9dagogique de l\u2019Universit\u00e9 du bridge pendant 20 ans. Champion d\u2019Europe par \u00e9quipes, champion du monde seniors, il a \u00e9t\u00e9 sacr\u00e9 champion du monde par \u00e9quipes mixtes en 2022. Plus qu\u2019un joueur, il est aussi journaliste pour Le Bridgeur.\",\"url\":\"https:\/\/funbridge.com\/blog\/author\/pcronier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un appel, \u00e7a ? - Blog Funbridge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/","og_locale":"fr_FR","og_type":"article","og_title":"Un appel, \u00e7a ? - Blog Funbridge","og_description":"\u00c9ternelle question du bridgeur&#8230; \u00e0 qui la faute, quel est le coupable ? Cet article est d\u00e9di\u00e9 \u00e0 un domaine pr\u00e9texte \u00e0 bien des discussions au sortir des tournois, la signalisation. Il est 17 heures, l\u2019heure de prendre place pour le duplicate d\u2019entra\u00eenement quotidien en ligne. En Est-Ouest, un couple encore jeune qui vise \u00e0 bien figurer dans les prochaines \u00e9preuves mixtes. En Sud, un petit requin des salles num\u00e9riques qui prend un malin plaisir \u00e0 mystifier tout le monde \u00e0 la table, \u00e0 commencer par son partenaire, s\u00e9rieux et bien \u00e9lev\u00e9. Apr\u00e8s deux donnes banales, voici le diagramme qui\u2026","og_url":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/","og_site_name":"Blog Funbridge","article_publisher":"https:\/\/www.facebook.com\/Funbridge\/","article_published_time":"2022-10-03T04:30:00+00:00","article_modified_time":"2025-07-03T12:50:30+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg","type":"image\/jpeg"}],"author":"Philippe Cronier","twitter_card":"summary_large_image","twitter_creator":"@funbridge","twitter_site":"@funbridge","twitter_misc":{"\u00c9crit par":"Philippe Cronier","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#article","isPartOf":{"@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/"},"author":{"name":"Philippe Cronier","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85"},"headline":"Un appel, \u00e7a&nbsp;?","datePublished":"2022-10-03T04:30:00+00:00","dateModified":"2025-07-03T12:50:30+00:00","mainEntityOfPage":{"@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/"},"wordCount":861,"commentCount":0,"publisher":{"@id":"https:\/\/funbridge.com\/blog\/#organization"},"image":{"@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage"},"thumbnailUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg","keywords":["analyse de donnes"],"articleSection":["Cours et exercices de bridge"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/","url":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/","name":"Un appel, \u00e7a ? - Blog Funbridge","isPartOf":{"@id":"https:\/\/funbridge.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage"},"image":{"@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage"},"thumbnailUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg","datePublished":"2022-10-03T04:30:00+00:00","dateModified":"2025-07-03T12:50:30+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/funbridge.com\/blog\/fr\/whose-fault\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/funbridge.com\/blog\/fr\/whose-fault\/#primaryimage","url":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg","contentUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/whose-fault.jpg","width":1920,"height":1080,"caption":"Whose fault"},{"@type":"WebSite","@id":"https:\/\/funbridge.com\/blog\/#website","url":"https:\/\/funbridge.com\/blog\/","name":"Blog Funbridge","description":"Toute l&#039;actualit\u00e9 du bridge et de FunBridge en un clin d&#039;\u0153il","publisher":{"@id":"https:\/\/funbridge.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/funbridge.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/funbridge.com\/blog\/#organization","name":"Funbridge","url":"https:\/\/funbridge.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png","contentUrl":"https:\/\/funbridge.com\/blog\/wp-content\/uploads\/Funbridge_Blog.png","width":610,"height":148,"caption":"Funbridge"},"image":{"@id":"https:\/\/funbridge.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Funbridge\/","https:\/\/x.com\/funbridge"]},{"@type":"Person","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/person\/30dba78c83367e5e371fb1e46d175d85","name":"Philippe Cronier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/funbridge.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png","contentUrl":"https:\/\/www.funbridge.com\/blog\/wp-content\/uploads\/cropped-Philippe-Cronier-1.png","caption":"Philippe Cronier"},"description":"Ce joueur redoutable est n\u00e9 \u00e0 Ermont, pr\u00e8s de Paris. Il a \u00e9t\u00e9 le directeur p\u00e9dagogique de l\u2019Universit\u00e9 du bridge pendant 20 ans. Champion d\u2019Europe par \u00e9quipes, champion du monde seniors, il a \u00e9t\u00e9 sacr\u00e9 champion du monde par \u00e9quipes mixtes en 2022. Plus qu\u2019un joueur, il est aussi journaliste pour Le Bridgeur.","url":"https:\/\/funbridge.com\/blog\/author\/pcronier\/"}]}},"lang":"fr","translations":{"fr":52122,"en":52143},"language":"fr","pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts\/52122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/comments?post=52122"}],"version-history":[{"count":14,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts\/52122\/revisions"}],"predecessor-version":[{"id":52163,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/posts\/52122\/revisions\/52163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/media\/52126"}],"wp:attachment":[{"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/media?parent=52122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/categories?post=52122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/tags?post=52122"},{"taxonomy":"access","embeddable":true,"href":"https:\/\/funbridge.com\/blog\/wp-json\/wp\/v2\/access?post=52122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}